{"id":21176,"date":"2023-11-15T11:28:00","date_gmt":"2023-11-15T11:28:00","guid":{"rendered":"http:\/\/www.ppdelugo.com\/o-pp-apoia-ao-sector-da-limpeza-na-sua-reivindicacion-dun-convenio-con-melloras-sociais-e-salariais\/"},"modified":"2023-11-15T12:39:43","modified_gmt":"2023-11-15T12:39:43","slug":"o-pp-apoia-ao-sector-da-limpeza-na-sua-reivindicacion-dun-convenio-con-melloras-sociais-e-salariais","status":"publish","type":"post","link":"https:\/\/www.ppdelugo.com\/es\/o-pp-apoia-ao-sector-da-limpeza-na-sua-reivindicacion-dun-convenio-con-melloras-sociais-e-salariais\/","title":{"rendered":"El PP apoya al sector de la limpieza  en su reivindicaci\u00f3n de un convenio con mejoras sociales y salariales"},"content":{"rendered":"<p>MI\u00c9RCOLES 15 DE NOVIEMBRE DE 2023<\/p>\n<p>\u2022 Los populares comparten y se suman a las revindicaci\u00f3ns del personal de limpieza de \u201cdignificar esta profesi\u00f3n\u201d recordando c\u00f3mo \u201clas de Lugo son las peor pagadas del sector, cuyos sueldos est\u00e1n a la cola en Espa\u00f1a\u201d y a\u00f1adiendo que \u201cestamos hablando de un sector fuertemente feminizado ya que el 95% de su personal son mujeres y donde existe un alto nivel de precariedad\u201d<\/p>\n<p>\u2022 Los populares aseguran que \u201clos pol\u00edticos tenemos la responsabilidad de no olvidar el papel esencial de las limpiadoras, un trabajo que tanto se elogi\u00f3 y que se visibiliz\u00f3, durante la pandemia\u201d<\/p>\n<p>\u2022 Los populares que mantuvieron en las \u00faltimas semanas varias reuniones con las centrales sindicales de la CIG, CC.OO y UGT analizaron con sus representantes diferentes cuestiones que \u201cpodr\u00edan ser interesantes y de futuro para el sector\u201d.<\/p>\n<p>\u2022 En este momento la negociaci\u00f3n del convenio provincial de la limpieza es la prioridad por lo que los populares, teniendo en cuenta que se trata de un servicio esencial, se comprometieron a trasladar a los agentes, que pueden colaborar para desbloquear este conflicto, las peticiones que les hicieron llegar en estos encuentros de trabajo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>MI\u00c9RCOLES 15 DE NOVIEMBRE DE 2023 \u2022 Los populares comparten y se suman a las revindicaci\u00f3ns del personal de limpieza de \u201cdignificar esta profesi\u00f3n\u201d recordando c\u00f3mo \u201clas de Lugo son&#8230;<\/p>\n","protected":false},"author":2,"featured_media":21179,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[98],"tags":[],"class_list":["post-21176","post","type-post","status-publish","format-standard","has-post-thumbnail","category-limpeza-es"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El PP apoya al sector de la limpieza en su reivindicaci\u00f3n de un convenio con mejoras sociales y salariales - Grupo Municipal Partido Popular de Lugo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ppdelugo.com\/es\/o-pp-apoia-ao-sector-da-limpeza-na-sua-reivindicacion-dun-convenio-con-melloras-sociais-e-salariais\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El PP apoya al sector de la limpieza en su reivindicaci\u00f3n de un convenio con mejoras sociales y salariales - Grupo Municipal Partido Popular de Lugo\" \/>\n<meta property=\"og:description\" content=\"MI\u00c9RCOLES 15 DE NOVIEMBRE DE 2023 \u2022 Los populares comparten y se suman a las revindicaci\u00f3ns del personal de limpieza de \u201cdignificar esta profesi\u00f3n\u201d recordando c\u00f3mo \u201clas de Lugo son...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ppdelugo.com\/es\/o-pp-apoia-ao-sector-da-limpeza-na-sua-reivindicacion-dun-convenio-con-melloras-sociais-e-salariais\/\" \/>\n<meta property=\"og:site_name\" content=\"Grupo Municipal Partido Popular de Lugo\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-15T11:28:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-15T12:39:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ppdelugo.com\/wp-content\/uploads\/2023\/11\/REUNION-SINDICATOS-LIMPIEZA.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1868\" \/>\n\t<meta property=\"og:image:height\" content=\"864\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"PP\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.ppdelugo.com\/wp-content\/uploads\/2023\/11\/REUNION-SINDICATOS-LIMPIEZA.jpeg\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"PP\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.ppdelugo.com\\\/es\\\/o-pp-apoia-ao-sector-da-limpeza-na-sua-reivindicacion-dun-convenio-con-melloras-sociais-e-salariais\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ppdelugo.com\\\/es\\\/o-pp-apoia-ao-sector-da-limpeza-na-sua-reivindicacion-dun-convenio-con-melloras-sociais-e-salariais\\\/\"},\"author\":{\"name\":\"PP\",\"@id\":\"https:\\\/\\\/www.ppdelugo.com\\\/es\\\/#\\\/schema\\\/person\\\/a847ea797b54208d374f6a8953571050\"},\"headline\":\"El PP apoya al sector de la limpieza en su reivindicaci\u00f3n de un convenio con mejoras sociales y salariales\",\"datePublished\":\"2023-11-15T11:28:00+00:00\",\"dateModified\":\"2023-11-15T12:39:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.ppdelugo.com\\\/es\\\/o-pp-apoia-ao-sector-da-limpeza-na-sua-reivindicacion-dun-convenio-con-melloras-sociais-e-salariais\\\/\"},\"wordCount\":218,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.ppdelugo.com\\\/es\\\/o-pp-apoia-ao-sector-da-limpeza-na-sua-reivindicacion-dun-convenio-con-melloras-sociais-e-salariais\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ppdelugo.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/REUNION-SINDICATOS-LIMPIEZA.jpeg\",\"articleSection\":[\"Limpeza\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.ppdelugo.com\\\/es\\\/o-pp-apoia-ao-sector-da-limpeza-na-sua-reivindicacion-dun-convenio-con-melloras-sociais-e-salariais\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ppdelugo.com\\\/es\\\/o-pp-apoia-ao-sector-da-limpeza-na-sua-reivindicacion-dun-convenio-con-melloras-sociais-e-salariais\\\/\",\"url\":\"https:\\\/\\\/www.ppdelugo.com\\\/es\\\/o-pp-apoia-ao-sector-da-limpeza-na-sua-reivindicacion-dun-convenio-con-melloras-sociais-e-salariais\\\/\",\"name\":\"El PP apoya al sector de la limpieza en su reivindicaci\u00f3n de un convenio con mejoras sociales y salariales - Grupo Municipal Partido Popular de Lugo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ppdelugo.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ppdelugo.com\\\/es\\\/o-pp-apoia-ao-sector-da-limpeza-na-sua-reivindicacion-dun-convenio-con-melloras-sociais-e-salariais\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ppdelugo.com\\\/es\\\/o-pp-apoia-ao-sector-da-limpeza-na-sua-reivindicacion-dun-convenio-con-melloras-sociais-e-salariais\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ppdelugo.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/REUNION-SINDICATOS-LIMPIEZA.jpeg\",\"datePublished\":\"2023-11-15T11:28:00+00:00\",\"dateModified\":\"2023-11-15T12:39:43+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.ppdelugo.com\\\/es\\\/#\\\/schema\\\/person\\\/a847ea797b54208d374f6a8953571050\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ppdelugo.com\\\/es\\\/o-pp-apoia-ao-sector-da-limpeza-na-sua-reivindicacion-dun-convenio-con-melloras-sociais-e-salariais\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ppdelugo.com\\\/es\\\/o-pp-apoia-ao-sector-da-limpeza-na-sua-reivindicacion-dun-convenio-con-melloras-sociais-e-salariais\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.ppdelugo.com\\\/es\\\/o-pp-apoia-ao-sector-da-limpeza-na-sua-reivindicacion-dun-convenio-con-melloras-sociais-e-salariais\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ppdelugo.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/REUNION-SINDICATOS-LIMPIEZA.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.ppdelugo.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/REUNION-SINDICATOS-LIMPIEZA.jpeg\",\"width\":1868,\"height\":864},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ppdelugo.com\\\/es\\\/o-pp-apoia-ao-sector-da-limpeza-na-sua-reivindicacion-dun-convenio-con-melloras-sociais-e-salariais\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.ppdelugo.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El PP apoya al sector de la limpieza en su reivindicaci\u00f3n de un convenio con mejoras sociales y salariales\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ppdelugo.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.ppdelugo.com\\\/es\\\/\",\"name\":\"Grupo Municipal Partido Popular de Lugo\",\"description\":\"Web del Grupo Municipal del Partido Popular en el Ayuntamiento de Lugo, con informaci\u00f3n sobre Lugo y fomento de la participaci\u00f3n ciudadana\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ppdelugo.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.ppdelugo.com\\\/es\\\/#\\\/schema\\\/person\\\/a847ea797b54208d374f6a8953571050\",\"name\":\"PP\",\"url\":\"https:\\\/\\\/www.ppdelugo.com\\\/es\\\/author\\\/ppdelugo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El PP apoya al sector de la limpieza en su reivindicaci\u00f3n de un convenio con mejoras sociales y salariales - Grupo Municipal Partido Popular de Lugo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ppdelugo.com\/es\/o-pp-apoia-ao-sector-da-limpeza-na-sua-reivindicacion-dun-convenio-con-melloras-sociais-e-salariais\/","og_locale":"es_ES","og_type":"article","og_title":"El PP apoya al sector de la limpieza en su reivindicaci\u00f3n de un convenio con mejoras sociales y salariales - Grupo Municipal Partido Popular de Lugo","og_description":"MI\u00c9RCOLES 15 DE NOVIEMBRE DE 2023 \u2022 Los populares comparten y se suman a las revindicaci\u00f3ns del personal de limpieza de \u201cdignificar esta profesi\u00f3n\u201d recordando c\u00f3mo \u201clas de Lugo son...","og_url":"https:\/\/www.ppdelugo.com\/es\/o-pp-apoia-ao-sector-da-limpeza-na-sua-reivindicacion-dun-convenio-con-melloras-sociais-e-salariais\/","og_site_name":"Grupo Municipal Partido Popular de Lugo","article_published_time":"2023-11-15T11:28:00+00:00","article_modified_time":"2023-11-15T12:39:43+00:00","og_image":[{"width":1868,"height":864,"url":"https:\/\/www.ppdelugo.com\/wp-content\/uploads\/2023\/11\/REUNION-SINDICATOS-LIMPIEZA.jpeg","type":"image\/jpeg"}],"author":"PP","twitter_card":"summary_large_image","twitter_image":"https:\/\/www.ppdelugo.com\/wp-content\/uploads\/2023\/11\/REUNION-SINDICATOS-LIMPIEZA.jpeg","twitter_misc":{"Escrito por":"PP","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ppdelugo.com\/es\/o-pp-apoia-ao-sector-da-limpeza-na-sua-reivindicacion-dun-convenio-con-melloras-sociais-e-salariais\/#article","isPartOf":{"@id":"https:\/\/www.ppdelugo.com\/es\/o-pp-apoia-ao-sector-da-limpeza-na-sua-reivindicacion-dun-convenio-con-melloras-sociais-e-salariais\/"},"author":{"name":"PP","@id":"https:\/\/www.ppdelugo.com\/es\/#\/schema\/person\/a847ea797b54208d374f6a8953571050"},"headline":"El PP apoya al sector de la limpieza en su reivindicaci\u00f3n de un convenio con mejoras sociales y salariales","datePublished":"2023-11-15T11:28:00+00:00","dateModified":"2023-11-15T12:39:43+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ppdelugo.com\/es\/o-pp-apoia-ao-sector-da-limpeza-na-sua-reivindicacion-dun-convenio-con-melloras-sociais-e-salariais\/"},"wordCount":218,"commentCount":0,"image":{"@id":"https:\/\/www.ppdelugo.com\/es\/o-pp-apoia-ao-sector-da-limpeza-na-sua-reivindicacion-dun-convenio-con-melloras-sociais-e-salariais\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ppdelugo.com\/wp-content\/uploads\/2023\/11\/REUNION-SINDICATOS-LIMPIEZA.jpeg","articleSection":["Limpeza"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.ppdelugo.com\/es\/o-pp-apoia-ao-sector-da-limpeza-na-sua-reivindicacion-dun-convenio-con-melloras-sociais-e-salariais\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.ppdelugo.com\/es\/o-pp-apoia-ao-sector-da-limpeza-na-sua-reivindicacion-dun-convenio-con-melloras-sociais-e-salariais\/","url":"https:\/\/www.ppdelugo.com\/es\/o-pp-apoia-ao-sector-da-limpeza-na-sua-reivindicacion-dun-convenio-con-melloras-sociais-e-salariais\/","name":"El PP apoya al sector de la limpieza en su reivindicaci\u00f3n de un convenio con mejoras sociales y salariales - Grupo Municipal Partido Popular de Lugo","isPartOf":{"@id":"https:\/\/www.ppdelugo.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ppdelugo.com\/es\/o-pp-apoia-ao-sector-da-limpeza-na-sua-reivindicacion-dun-convenio-con-melloras-sociais-e-salariais\/#primaryimage"},"image":{"@id":"https:\/\/www.ppdelugo.com\/es\/o-pp-apoia-ao-sector-da-limpeza-na-sua-reivindicacion-dun-convenio-con-melloras-sociais-e-salariais\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ppdelugo.com\/wp-content\/uploads\/2023\/11\/REUNION-SINDICATOS-LIMPIEZA.jpeg","datePublished":"2023-11-15T11:28:00+00:00","dateModified":"2023-11-15T12:39:43+00:00","author":{"@id":"https:\/\/www.ppdelugo.com\/es\/#\/schema\/person\/a847ea797b54208d374f6a8953571050"},"breadcrumb":{"@id":"https:\/\/www.ppdelugo.com\/es\/o-pp-apoia-ao-sector-da-limpeza-na-sua-reivindicacion-dun-convenio-con-melloras-sociais-e-salariais\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ppdelugo.com\/es\/o-pp-apoia-ao-sector-da-limpeza-na-sua-reivindicacion-dun-convenio-con-melloras-sociais-e-salariais\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.ppdelugo.com\/es\/o-pp-apoia-ao-sector-da-limpeza-na-sua-reivindicacion-dun-convenio-con-melloras-sociais-e-salariais\/#primaryimage","url":"https:\/\/www.ppdelugo.com\/wp-content\/uploads\/2023\/11\/REUNION-SINDICATOS-LIMPIEZA.jpeg","contentUrl":"https:\/\/www.ppdelugo.com\/wp-content\/uploads\/2023\/11\/REUNION-SINDICATOS-LIMPIEZA.jpeg","width":1868,"height":864},{"@type":"BreadcrumbList","@id":"https:\/\/www.ppdelugo.com\/es\/o-pp-apoia-ao-sector-da-limpeza-na-sua-reivindicacion-dun-convenio-con-melloras-sociais-e-salariais\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.ppdelugo.com\/es\/"},{"@type":"ListItem","position":2,"name":"El PP apoya al sector de la limpieza en su reivindicaci\u00f3n de un convenio con mejoras sociales y salariales"}]},{"@type":"WebSite","@id":"https:\/\/www.ppdelugo.com\/es\/#website","url":"https:\/\/www.ppdelugo.com\/es\/","name":"Grupo Municipal Partido Popular de Lugo","description":"Web del Grupo Municipal del Partido Popular en el Ayuntamiento de Lugo, con informaci\u00f3n sobre Lugo y fomento de la participaci\u00f3n ciudadana","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ppdelugo.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.ppdelugo.com\/es\/#\/schema\/person\/a847ea797b54208d374f6a8953571050","name":"PP","url":"https:\/\/www.ppdelugo.com\/es\/author\/ppdelugo\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ppdelugo.com\/es\/wp-json\/wp\/v2\/posts\/21176","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ppdelugo.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ppdelugo.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ppdelugo.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ppdelugo.com\/es\/wp-json\/wp\/v2\/comments?post=21176"}],"version-history":[{"count":2,"href":"https:\/\/www.ppdelugo.com\/es\/wp-json\/wp\/v2\/posts\/21176\/revisions"}],"predecessor-version":[{"id":21178,"href":"https:\/\/www.ppdelugo.com\/es\/wp-json\/wp\/v2\/posts\/21176\/revisions\/21178"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ppdelugo.com\/es\/wp-json\/wp\/v2\/media\/21179"}],"wp:attachment":[{"href":"https:\/\/www.ppdelugo.com\/es\/wp-json\/wp\/v2\/media?parent=21176"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ppdelugo.com\/es\/wp-json\/wp\/v2\/categories?post=21176"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ppdelugo.com\/es\/wp-json\/wp\/v2\/tags?post=21176"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}