{"id":15759,"date":"2021-08-23T09:56:09","date_gmt":"2021-08-23T09:56:09","guid":{"rendered":"http:\/\/www.ppdelugo.com\/o-pp-denuncia-que-na-primeira-metade-do-ano-so-o-18-das-licenzas-resoltas-para-a-cidade-se-concederon-en-menos-de-90-dias\/"},"modified":"2021-08-23T09:56:38","modified_gmt":"2021-08-23T09:56:38","slug":"o-pp-denuncia-que-na-primeira-metade-do-ano-so-o-18-das-licenzas-resoltas-para-a-cidade-se-concederon-en-menos-de-90-dias","status":"publish","type":"post","link":"https:\/\/www.ppdelugo.com\/es\/o-pp-denuncia-que-na-primeira-metade-do-ano-so-o-18-das-licenzas-resoltas-para-a-cidade-se-concederon-en-menos-de-90-dias\/","title":{"rendered":"El PP denuncia que en la primera mitad del a\u00f1o solo el 18% de las licencias resueltas para la ciudad se concedieron en menos de 90 d\u00edas"},"content":{"rendered":"<p>El concejal del Grupo Municipal del PP Manuel L\u00f3pez lamenta que el gobierno local so concediera dentro del plazo legal establecido, que es de 90 d\u00edas, 20 de las 111 licencias aprobadas para el \u00e1mbito urbano nos primeros seis meses del a\u00f1o, un claro s\u00edntoma de un gobierno bloqueado y paralizado en el que las reyertas internas ya propiciaron incluso la dimisi\u00f3n de un concejal<\/p>\n<p><!--more--><\/p>\n<p>Semella que o goberno local liderado por Lara M\u00e9ndez e Rub\u00e9n Arroxo non aprende dos erros do pasado e lonxe de po\u00f1erse a traballar en prol da mellora da vida dos lucenses, seguen enfrascados na s\u00faa marcaxe persoal, con dimisi\u00f3ns de concelleiros inclu\u00eddas, paralizando a actividade municipal.<\/p>\n<p>O concelleiro popular Manuel L\u00f3pez fai esta reflexi\u00f3n despois de avaliar os datos obtidos das licenzas aprobadas nos primeiros seis meses do ano para o \u00e1mbito urbano, uns datos \u201cdesastrosos\u201d que amosan \u00e1s claras \u201ca falta de traballo dun equipo de goberno desgastado e superado pola realidade\u201d.<\/p>\n<p>Se Lara M\u00e9ndez e Rub\u00e9n Arroxo pecharon o ano 2020 situando o prazo medio para a resoluci\u00f3n dunha licenza no eido urbano en 330 d\u00edas de media, o inicio de 2021 non foi positivo, xa que nos primeiros seis meses do ano este dato disparouse ata os 420 d\u00edas de media, \u201cun dato que amosa claramente que o mellor \u00e9 un relevo \u00e1 fronte do goberno local\u201d.<\/p>\n<p>Manuel L\u00f3pez amosouse moi preocupado despois de analizar estes datos, xunto aos que xa se fixeron p\u00fablicos a semana pasada sobre o referente \u00e1s parroquias do rural, que amosan unha sintomatolox\u00eda clara: \u201cen Lugo temos un goberno que est\u00e1 a debullar un panorama desolador\u201d.<\/p>\n<p>Explica o concelleiro popular que todos estes datos referentes \u00e1 resoluci\u00f3n de licenzas obtiv\u00e9ronse das actas das xuntas de goberno local, polo que \u201ca ver que escusa se sacan da manga agora tanto M\u00e9ndez como Arroxo para tentar lavar a cara\u201d.<\/p>\n<p>Durante os primeiros seis meses do ano, no \u00e1mbito urbano, resolv\u00e9ronse 111 solicitudes de licenza, das que so 20 se tramitaron dentro dos 90 d\u00edas que marca a lei, \u00e9 dicir, s\u00f3 o 18% das solicitudes de licenza resoltas durante os primeiros seis meses do ano cumpriron os prazos legais establecidos. Seguramente, o goberno local recupere a escusa de que son os particulares os que ralentizan a tramitaci\u00f3n, circunstancia que aproveita o concelleiro popular para enviar unha pregunta directa ao equipo de goberno: \u201cde verdade pensan que un particular que quere realizar unha obra vai a paralizar a s\u00faa petici\u00f3n?. Dicir iso \u00e9 facerse trampas ao solitario\u201d.<\/p>\n<p>No informe elaborado polos populares hai datos reveladores como que, de media, ning\u00fan dos aspectos avaliados cumpre o prazo marcado na lei.<\/p>\n<p>&nbsp;<\/p>\n<table width=\"621\">\n<tbody>\n<tr>\n<td width=\"101\"><strong>Tipo de obra<\/strong><\/td>\n<td width=\"120\"><strong>Media (en d\u00edas)<\/strong><\/td>\n<td width=\"167\"><strong>Prazo M\u00e1ximo (en d\u00edas)<\/strong><\/td>\n<td width=\"120\"><strong>Importe medio<\/strong><\/td>\n<td width=\"113\"><strong>Importe total<\/strong><\/td>\n<\/tr>\n<tr>\n<td width=\"101\">Ascensores<\/td>\n<td width=\"120\">182<\/td>\n<td width=\"167\">660<\/td>\n<td width=\"120\">51.284,46 \u20ac<\/td>\n<td width=\"113\">974.404,73 \u20ac<\/td>\n<\/tr>\n<tr>\n<td width=\"101\">Edifico<\/td>\n<td width=\"120\">492<\/td>\n<td width=\"167\">1560<\/td>\n<td width=\"120\">321.141,62 \u20ac<\/td>\n<td width=\"113\">9.313.107,07 \u20ac<\/td>\n<\/tr>\n<tr>\n<td width=\"101\">Outros<\/td>\n<td width=\"120\">493<\/td>\n<td width=\"167\">1721<\/td>\n<td width=\"120\">260.224,12 \u20ac<\/td>\n<td width=\"113\">6.505.602,89 \u20ac<\/td>\n<\/tr>\n<tr>\n<td width=\"101\">Reformas<\/td>\n<td width=\"120\">420<\/td>\n<td width=\"167\">2701<\/td>\n<td width=\"120\">74.630,41 \u20ac<\/td>\n<td width=\"113\">1.791.129,84 \u20ac<\/td>\n<\/tr>\n<tr>\n<td width=\"101\">Tellados<\/td>\n<td width=\"120\">377<\/td>\n<td width=\"167\">524<\/td>\n<td width=\"120\">33.510,75 \u20ac<\/td>\n<td width=\"113\">67.021,50 \u20ac<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p>A realidade \u00e9 que tanto Lara M\u00e9ndez coma Rub\u00e9n Arroxo est\u00e1n a po\u00f1er en risco numerosos postos de traballo, xa que a construci\u00f3n \u00e9 un dos principais motores econ\u00f3micos da cidade e que tendo en conta so as licenzas avaliadas para o \u00e1mbito urbano nos primeiros seis meses do ano xeraron un volume de negocio de 18.651.266,03 \u20ac.<\/p>\n<p>Chegados a este punto, dende o Grupo Municipal Popular esixen ao goberno local unha \u201creacci\u00f3n inmediata que non se pode demorar m\u00e1is\u201d e que pasa polo reforzo do persoal de todos os departamentos que interve\u00f1en na resoluci\u00f3n de licenzas, xa que \u201cnos consta que todo o persoal que interv\u00e9n no proceso est\u00e1 a dar o 110%, polo que urxe un reforzo para axudar a aliviar a carga de traballo e axilizar a resoluci\u00f3n das petici\u00f3ns de licenza\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El concejal del Grupo Municipal del PP Manuel L\u00f3pez lamenta que el gobierno local so concediera dentro del plazo legal establecido, que es de 90 d\u00edas, 20 de las 111&#8230;<\/p>\n","protected":false},"author":2,"featured_media":14798,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[42],"tags":[],"class_list":{"0":"post-15759","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-urbanismo-es"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El PP denuncia que en la primera mitad del a\u00f1o solo el 18% de las licencias resueltas para la ciudad se concedieron en menos de 90 d\u00edas - Grupo Municipal Partido Popular de Lugo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ppdelugo.com\/es\/o-pp-denuncia-que-na-primeira-metade-do-ano-so-o-18-das-licenzas-resoltas-para-a-cidade-se-concederon-en-menos-de-90-dias\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El PP denuncia que en la primera mitad del a\u00f1o solo el 18% de las licencias resueltas para la ciudad se concedieron en menos de 90 d\u00edas - Grupo Municipal Partido Popular de Lugo\" \/>\n<meta property=\"og:description\" content=\"El concejal del Grupo Municipal del PP Manuel L\u00f3pez lamenta que el gobierno local so concediera dentro del plazo legal establecido, que es de 90 d\u00edas, 20 de las 111...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ppdelugo.com\/es\/o-pp-denuncia-que-na-primeira-metade-do-ano-so-o-18-das-licenzas-resoltas-para-a-cidade-se-concederon-en-menos-de-90-dias\/\" \/>\n<meta property=\"og:site_name\" content=\"Grupo Municipal Partido Popular de Lugo\" \/>\n<meta property=\"article:published_time\" content=\"2021-08-23T09:56:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-08-23T09:56:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ppdelugo.com\/wp-content\/uploads\/2021\/04\/Gruas-sen-traballo-licenzas-paradas-min-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"PP\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"PP\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.ppdelugo.com\\\/es\\\/o-pp-denuncia-que-na-primeira-metade-do-ano-so-o-18-das-licenzas-resoltas-para-a-cidade-se-concederon-en-menos-de-90-dias\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ppdelugo.com\\\/es\\\/o-pp-denuncia-que-na-primeira-metade-do-ano-so-o-18-das-licenzas-resoltas-para-a-cidade-se-concederon-en-menos-de-90-dias\\\/\"},\"author\":{\"name\":\"PP\",\"@id\":\"https:\\\/\\\/www.ppdelugo.com\\\/es\\\/#\\\/schema\\\/person\\\/a847ea797b54208d374f6a8953571050\"},\"headline\":\"El PP denuncia que en la primera mitad del a\u00f1o solo el 18% de las licencias resueltas para la ciudad se concedieron en menos de 90 d\u00edas\",\"datePublished\":\"2021-08-23T09:56:09+00:00\",\"dateModified\":\"2021-08-23T09:56:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.ppdelugo.com\\\/es\\\/o-pp-denuncia-que-na-primeira-metade-do-ano-so-o-18-das-licenzas-resoltas-para-a-cidade-se-concederon-en-menos-de-90-dias\\\/\"},\"wordCount\":648,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.ppdelugo.com\\\/es\\\/o-pp-denuncia-que-na-primeira-metade-do-ano-so-o-18-das-licenzas-resoltas-para-a-cidade-se-concederon-en-menos-de-90-dias\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ppdelugo.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/Gruas-sen-traballo-licenzas-paradas-min-scaled.jpg\",\"articleSection\":[\"Urbanismo\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.ppdelugo.com\\\/es\\\/o-pp-denuncia-que-na-primeira-metade-do-ano-so-o-18-das-licenzas-resoltas-para-a-cidade-se-concederon-en-menos-de-90-dias\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ppdelugo.com\\\/es\\\/o-pp-denuncia-que-na-primeira-metade-do-ano-so-o-18-das-licenzas-resoltas-para-a-cidade-se-concederon-en-menos-de-90-dias\\\/\",\"url\":\"https:\\\/\\\/www.ppdelugo.com\\\/es\\\/o-pp-denuncia-que-na-primeira-metade-do-ano-so-o-18-das-licenzas-resoltas-para-a-cidade-se-concederon-en-menos-de-90-dias\\\/\",\"name\":\"El PP denuncia que en la primera mitad del a\u00f1o solo el 18% de las licencias resueltas para la ciudad se concedieron en menos de 90 d\u00edas - Grupo Municipal Partido Popular de Lugo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ppdelugo.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ppdelugo.com\\\/es\\\/o-pp-denuncia-que-na-primeira-metade-do-ano-so-o-18-das-licenzas-resoltas-para-a-cidade-se-concederon-en-menos-de-90-dias\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ppdelugo.com\\\/es\\\/o-pp-denuncia-que-na-primeira-metade-do-ano-so-o-18-das-licenzas-resoltas-para-a-cidade-se-concederon-en-menos-de-90-dias\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ppdelugo.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/Gruas-sen-traballo-licenzas-paradas-min-scaled.jpg\",\"datePublished\":\"2021-08-23T09:56:09+00:00\",\"dateModified\":\"2021-08-23T09:56:38+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.ppdelugo.com\\\/es\\\/#\\\/schema\\\/person\\\/a847ea797b54208d374f6a8953571050\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ppdelugo.com\\\/es\\\/o-pp-denuncia-que-na-primeira-metade-do-ano-so-o-18-das-licenzas-resoltas-para-a-cidade-se-concederon-en-menos-de-90-dias\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ppdelugo.com\\\/es\\\/o-pp-denuncia-que-na-primeira-metade-do-ano-so-o-18-das-licenzas-resoltas-para-a-cidade-se-concederon-en-menos-de-90-dias\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.ppdelugo.com\\\/es\\\/o-pp-denuncia-que-na-primeira-metade-do-ano-so-o-18-das-licenzas-resoltas-para-a-cidade-se-concederon-en-menos-de-90-dias\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ppdelugo.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/Gruas-sen-traballo-licenzas-paradas-min-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.ppdelugo.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/Gruas-sen-traballo-licenzas-paradas-min-scaled.jpg\",\"width\":2560,\"height\":1920},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ppdelugo.com\\\/es\\\/o-pp-denuncia-que-na-primeira-metade-do-ano-so-o-18-das-licenzas-resoltas-para-a-cidade-se-concederon-en-menos-de-90-dias\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.ppdelugo.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El PP denuncia que en la primera mitad del a\u00f1o solo el 18% de las licencias resueltas para la ciudad se concedieron en menos de 90 d\u00edas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ppdelugo.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.ppdelugo.com\\\/es\\\/\",\"name\":\"Grupo Municipal Partido Popular de Lugo\",\"description\":\"Web del Grupo Municipal del Partido Popular en el Ayuntamiento de Lugo, con informaci\u00f3n sobre Lugo y fomento de la participaci\u00f3n ciudadana\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ppdelugo.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.ppdelugo.com\\\/es\\\/#\\\/schema\\\/person\\\/a847ea797b54208d374f6a8953571050\",\"name\":\"PP\",\"url\":\"https:\\\/\\\/www.ppdelugo.com\\\/es\\\/author\\\/ppdelugo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El PP denuncia que en la primera mitad del a\u00f1o solo el 18% de las licencias resueltas para la ciudad se concedieron en menos de 90 d\u00edas - Grupo Municipal Partido Popular de Lugo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ppdelugo.com\/es\/o-pp-denuncia-que-na-primeira-metade-do-ano-so-o-18-das-licenzas-resoltas-para-a-cidade-se-concederon-en-menos-de-90-dias\/","og_locale":"es_ES","og_type":"article","og_title":"El PP denuncia que en la primera mitad del a\u00f1o solo el 18% de las licencias resueltas para la ciudad se concedieron en menos de 90 d\u00edas - Grupo Municipal Partido Popular de Lugo","og_description":"El concejal del Grupo Municipal del PP Manuel L\u00f3pez lamenta que el gobierno local so concediera dentro del plazo legal establecido, que es de 90 d\u00edas, 20 de las 111...","og_url":"https:\/\/www.ppdelugo.com\/es\/o-pp-denuncia-que-na-primeira-metade-do-ano-so-o-18-das-licenzas-resoltas-para-a-cidade-se-concederon-en-menos-de-90-dias\/","og_site_name":"Grupo Municipal Partido Popular de Lugo","article_published_time":"2021-08-23T09:56:09+00:00","article_modified_time":"2021-08-23T09:56:38+00:00","og_image":[{"width":2560,"height":1920,"url":"https:\/\/www.ppdelugo.com\/wp-content\/uploads\/2021\/04\/Gruas-sen-traballo-licenzas-paradas-min-scaled.jpg","type":"image\/jpeg"}],"author":"PP","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"PP","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ppdelugo.com\/es\/o-pp-denuncia-que-na-primeira-metade-do-ano-so-o-18-das-licenzas-resoltas-para-a-cidade-se-concederon-en-menos-de-90-dias\/#article","isPartOf":{"@id":"https:\/\/www.ppdelugo.com\/es\/o-pp-denuncia-que-na-primeira-metade-do-ano-so-o-18-das-licenzas-resoltas-para-a-cidade-se-concederon-en-menos-de-90-dias\/"},"author":{"name":"PP","@id":"https:\/\/www.ppdelugo.com\/es\/#\/schema\/person\/a847ea797b54208d374f6a8953571050"},"headline":"El PP denuncia que en la primera mitad del a\u00f1o solo el 18% de las licencias resueltas para la ciudad se concedieron en menos de 90 d\u00edas","datePublished":"2021-08-23T09:56:09+00:00","dateModified":"2021-08-23T09:56:38+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ppdelugo.com\/es\/o-pp-denuncia-que-na-primeira-metade-do-ano-so-o-18-das-licenzas-resoltas-para-a-cidade-se-concederon-en-menos-de-90-dias\/"},"wordCount":648,"commentCount":0,"image":{"@id":"https:\/\/www.ppdelugo.com\/es\/o-pp-denuncia-que-na-primeira-metade-do-ano-so-o-18-das-licenzas-resoltas-para-a-cidade-se-concederon-en-menos-de-90-dias\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ppdelugo.com\/wp-content\/uploads\/2021\/04\/Gruas-sen-traballo-licenzas-paradas-min-scaled.jpg","articleSection":["Urbanismo"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.ppdelugo.com\/es\/o-pp-denuncia-que-na-primeira-metade-do-ano-so-o-18-das-licenzas-resoltas-para-a-cidade-se-concederon-en-menos-de-90-dias\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.ppdelugo.com\/es\/o-pp-denuncia-que-na-primeira-metade-do-ano-so-o-18-das-licenzas-resoltas-para-a-cidade-se-concederon-en-menos-de-90-dias\/","url":"https:\/\/www.ppdelugo.com\/es\/o-pp-denuncia-que-na-primeira-metade-do-ano-so-o-18-das-licenzas-resoltas-para-a-cidade-se-concederon-en-menos-de-90-dias\/","name":"El PP denuncia que en la primera mitad del a\u00f1o solo el 18% de las licencias resueltas para la ciudad se concedieron en menos de 90 d\u00edas - Grupo Municipal Partido Popular de Lugo","isPartOf":{"@id":"https:\/\/www.ppdelugo.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ppdelugo.com\/es\/o-pp-denuncia-que-na-primeira-metade-do-ano-so-o-18-das-licenzas-resoltas-para-a-cidade-se-concederon-en-menos-de-90-dias\/#primaryimage"},"image":{"@id":"https:\/\/www.ppdelugo.com\/es\/o-pp-denuncia-que-na-primeira-metade-do-ano-so-o-18-das-licenzas-resoltas-para-a-cidade-se-concederon-en-menos-de-90-dias\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ppdelugo.com\/wp-content\/uploads\/2021\/04\/Gruas-sen-traballo-licenzas-paradas-min-scaled.jpg","datePublished":"2021-08-23T09:56:09+00:00","dateModified":"2021-08-23T09:56:38+00:00","author":{"@id":"https:\/\/www.ppdelugo.com\/es\/#\/schema\/person\/a847ea797b54208d374f6a8953571050"},"breadcrumb":{"@id":"https:\/\/www.ppdelugo.com\/es\/o-pp-denuncia-que-na-primeira-metade-do-ano-so-o-18-das-licenzas-resoltas-para-a-cidade-se-concederon-en-menos-de-90-dias\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ppdelugo.com\/es\/o-pp-denuncia-que-na-primeira-metade-do-ano-so-o-18-das-licenzas-resoltas-para-a-cidade-se-concederon-en-menos-de-90-dias\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.ppdelugo.com\/es\/o-pp-denuncia-que-na-primeira-metade-do-ano-so-o-18-das-licenzas-resoltas-para-a-cidade-se-concederon-en-menos-de-90-dias\/#primaryimage","url":"https:\/\/www.ppdelugo.com\/wp-content\/uploads\/2021\/04\/Gruas-sen-traballo-licenzas-paradas-min-scaled.jpg","contentUrl":"https:\/\/www.ppdelugo.com\/wp-content\/uploads\/2021\/04\/Gruas-sen-traballo-licenzas-paradas-min-scaled.jpg","width":2560,"height":1920},{"@type":"BreadcrumbList","@id":"https:\/\/www.ppdelugo.com\/es\/o-pp-denuncia-que-na-primeira-metade-do-ano-so-o-18-das-licenzas-resoltas-para-a-cidade-se-concederon-en-menos-de-90-dias\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.ppdelugo.com\/es\/"},{"@type":"ListItem","position":2,"name":"El PP denuncia que en la primera mitad del a\u00f1o solo el 18% de las licencias resueltas para la ciudad se concedieron en menos de 90 d\u00edas"}]},{"@type":"WebSite","@id":"https:\/\/www.ppdelugo.com\/es\/#website","url":"https:\/\/www.ppdelugo.com\/es\/","name":"Grupo Municipal Partido Popular de Lugo","description":"Web del Grupo Municipal del Partido Popular en el Ayuntamiento de Lugo, con informaci\u00f3n sobre Lugo y fomento de la participaci\u00f3n ciudadana","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ppdelugo.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.ppdelugo.com\/es\/#\/schema\/person\/a847ea797b54208d374f6a8953571050","name":"PP","url":"https:\/\/www.ppdelugo.com\/es\/author\/ppdelugo\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ppdelugo.com\/es\/wp-json\/wp\/v2\/posts\/15759","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ppdelugo.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ppdelugo.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ppdelugo.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ppdelugo.com\/es\/wp-json\/wp\/v2\/comments?post=15759"}],"version-history":[{"count":2,"href":"https:\/\/www.ppdelugo.com\/es\/wp-json\/wp\/v2\/posts\/15759\/revisions"}],"predecessor-version":[{"id":15761,"href":"https:\/\/www.ppdelugo.com\/es\/wp-json\/wp\/v2\/posts\/15759\/revisions\/15761"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ppdelugo.com\/es\/wp-json\/wp\/v2\/media\/14798"}],"wp:attachment":[{"href":"https:\/\/www.ppdelugo.com\/es\/wp-json\/wp\/v2\/media?parent=15759"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ppdelugo.com\/es\/wp-json\/wp\/v2\/categories?post=15759"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ppdelugo.com\/es\/wp-json\/wp\/v2\/tags?post=15759"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}